{"id":3074,"date":"2023-05-27T14:37:54","date_gmt":"2023-05-27T12:37:54","guid":{"rendered":"https:\/\/tousenconcert.org\/?p=3074"},"modified":"2023-09-24T18:20:46","modified_gmt":"2023-09-24T16:20:46","slug":"prochain-recital-de-tous-en-concert-samedi-3-juin-2023-a-17-h-precises","status":"publish","type":"post","link":"https:\/\/tousenconcert.org\/es\/prochain-recital-de-tous-en-concert-samedi-3-juin-2023-a-17-h-precises\/","title":{"rendered":"R\u00e9cital du samedi 3 juin 2023"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3074\" class=\"elementor elementor-3074\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dd61739 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dd61739\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ad96523\" data-id=\"4ad96523\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2b04ef elementor-widget elementor-widget-heading\" data-id=\"a2b04ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9sentation<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f05bb5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f05bb5e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5634e302\" data-id=\"5634e302\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d4d0a71 elementor-widget elementor-widget-text-editor\" data-id=\"1d4d0a71\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61056db1\" data-id=\"61056db1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53a05650 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"53a05650\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dur\u00e9e : environ 2 heures<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-train\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-wheelchair\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b427656 elementor-widget elementor-widget-heading\" data-id=\"3b427656\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Programme<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6429cb8b elementor-widget elementor-widget-text-editor\" data-id=\"6429cb8b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><u>\u00a0<\/u><\/p><ul><li><strong>L.Beethoven<\/strong>, Sonata n\u00b032 Op.111 (1er mouvement)<\/li><\/ul><p><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Guilhelm Raillard, Piano\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><\/p><p>\u00a0<\/p><ul><li><strong>R.Schumann<\/strong>, Sonata n.1 Op.11<\/li><li><strong>M.Ravel<\/strong>, Sonatine M.40<\/li><\/ul><p><em>\u00a0 \u00a0 Julie Saito, Piano\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<br \/><br \/><\/em><\/p><ul><li><strong>A.Scriabin,\u00a0<\/strong>Etudes n.11, 5, 2 Op.8<\/li><\/ul><p><em>\u00a0 \u00a0 Guillaume Thomain, Piano\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/em><\/p><p>\u00a0<\/p><ul><li><strong>S.Rachmaninoff,<\/strong>\u00a0Sonata in G Minor par piano et violoncelle 4eme mouvement\u00a0<\/li><\/ul><p><em>\u00a0 \u00a0 \u00a0Fran\u00e7ois Meyrueix, Piano et Luc de Seze, Violoncelle<\/em><\/p><p>\u00a0<\/p><p><em>\u00a0 \u00a0 \u00a0 \u00a0Entracte<\/em><\/p><ul><li><strong>L.Berio<\/strong>&#8211; Wasserklavier, extrait des six \u00ab\u00a0encores\u00a0\u00bb pour piano<\/li><li><strong>S.Prokofiev<\/strong>&#8211; Sonate n.3 Op.28<\/li><\/ul><p><em>\u00a0 \u00a0 \u00a0 \u00a0 Julien Lombardo, Piano\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0<\/em><\/p><p>\u00a0<\/p><ul><li><strong>A.Scriabin,\u00a0<\/strong>Po\u00e8me n.1 Op. 32\u00a0<\/li><li><strong>F.Chopin<\/strong>, Etude \u00ab\u00a0Revolutionary\u00a0\u00bb, n.12 Op.10\u00a0<\/li><\/ul><ul><li><strong>F.Mendelssohn,\u00a0<\/strong>Fantaisie \u00ab\u00a0Sonate \u00e9cossaise\u00a0\u00bb\u00a0<\/li><\/ul><p><em>\u00a0 \u00a0 \u00a0Sho Yamasaki, Piano\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/em><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sentation Dur\u00e9e : environ 2 heures Programme \u00a0 L.Beethoven, Sonata n\u00b032 Op.111 (1er mouvement) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Guilhelm Raillard, Piano\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 R.Schumann, Sonata n.1 Op.11 M.Ravel, Sonatine M.40 \u00a0 \u00a0 Julie Saito, Piano\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>","protected":false},"author":8,"featured_media":2826,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6],"tags":[],"class_list":["post-3074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","category-evenements-passes"],"acf":[],"_links":{"self":[{"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/posts\/3074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/comments?post=3074"}],"version-history":[{"count":9,"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/posts\/3074\/revisions"}],"predecessor-version":[{"id":3102,"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/posts\/3074\/revisions\/3102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/media\/2826"}],"wp:attachment":[{"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/media?parent=3074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/categories?post=3074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tousenconcert.org\/es\/wp-json\/wp\/v2\/tags?post=3074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}