{"id":2773,"date":"2021-11-02T09:20:00","date_gmt":"2021-11-02T08:20:00","guid":{"rendered":"https:\/\/tousenconcert.org\/?post_type=extrait-musical&#038;p=2773"},"modified":"2023-01-16T11:25:52","modified_gmt":"2023-01-16T10:25:52","slug":"gerard-moutet-c-debussy-suite-bergamasque","status":"publish","type":"extrait-musical","link":"https:\/\/tousenconcert.org\/ru\/extrait-musical\/gerard-moutet-c-debussy-suite-bergamasque\/","title":{"rendered":"G\u00e9rard Moutet  C. Debussy : Suite bergamasque"},"content":{"rendered":"<p>R\u00e9cital de &lsquo;Tous en concert !&rsquo; du 27 novembre 2021<\/p>","protected":false},"excerpt":{"rendered":"<p>R\u00e9cital de &lsquo;Tous en concert !&rsquo; du 27 novembre 2021<\/p>","protected":false},"template":"","class_list":["post-2773","extrait-musical","type-extrait-musical","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tousenconcert.org\/ru\/wp-json\/wp\/v2\/extrait-musical\/2773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tousenconcert.org\/ru\/wp-json\/wp\/v2\/extrait-musical"}],"about":[{"href":"https:\/\/tousenconcert.org\/ru\/wp-json\/wp\/v2\/types\/extrait-musical"}],"version-history":[{"count":3,"href":"https:\/\/tousenconcert.org\/ru\/wp-json\/wp\/v2\/extrait-musical\/2773\/revisions"}],"predecessor-version":[{"id":2978,"href":"https:\/\/tousenconcert.org\/ru\/wp-json\/wp\/v2\/extrait-musical\/2773\/revisions\/2978"}],"wp:attachment":[{"href":"https:\/\/tousenconcert.org\/ru\/wp-json\/wp\/v2\/media?parent=2773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}